{"id":664,"date":"2021-11-14T01:43:47","date_gmt":"2021-11-14T01:43:47","guid":{"rendered":"https:\/\/prokat.k-tech.gr\/%ce%ad%cf%81%ce%b3%ce%b1\/"},"modified":"2026-07-02T09:37:45","modified_gmt":"2026-07-02T09:37:45","slug":"%ce%ad%cf%81%ce%b3%ce%b1","status":"publish","type":"page","link":"https:\/\/prokat.k-tech.gr\/el\/%ce%ad%cf%81%ce%b3%ce%b1\/","title":{"rendered":"\u0388\u03c1\u03b3\u03b1"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;13%&#8221; bottom_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; enable_gradient=&#8221;true&#8221; overlay_strength=&#8221;1&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_color=&#8221;#f4f4f4&#8243; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;40%&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;curve_opacity&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; enable_gradient=&#8221;true&#8221; overlay_strength=&#8221;1&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_color=&#8221;#f4f4f4&#8243; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;40%&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;curve_opacity&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;2%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#000000&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;\u0395\u03c0\u03b9\u03bb\u03b5\u03b3\u03bc\u03ad\u03bd\u03b1 \u0388\u03c1\u03b3\u03b1&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#131418&#8243; scene_position=&#8221;center&#8221; bottom_padding=&#8221;14%&#8221; top_padding_tablet=&#8221;20%&#8221; bottom_padding_tablet=&#8221;20%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;37%&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;fan&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_post_grid post_type=&#8221;portfolio&#8221; portfolio_category=&#8221;all&#8221; portfolio_starting_category=&#8221;all&#8221; order=&#8221;DESC&#8221; orderby=&#8221;title&#8221; pagination=&#8221;load-more&#8221; button_color=&#8221;accent-color&#8221; columns=&#8221;3&#8243; columns_tablet=&#8221;default&#8221; columns_phone=&#8221;default&#8221; grid_item_spacing=&#8221;10px&#8221; grid_item_height=&#8221;30vh&#8221; enable_sortable=&#8221;yes&#8221; sortable_alignment=&#8221;default&#8221; sortable_color=&#8221;extra-color-3&#8243; image_size=&#8221;portfolio-thumb_large&#8221; aspect_ratio_image_size=&#8221;yes&#8221; custom_image_aspect_ratio=&#8221;default&#8221; image_loading=&#8221;lazy-load&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_stagger=&#8221;90&#8243; animation_easing=&#8221;default&#8221; parallax_scrolling=&#8221;yes&#8221; heading_tag=&#8221;h4&#8243; heading_tag_render=&#8221;default&#8221; display_categories=&#8221;yes&#8221; category_functionality=&#8221;default&#8221; category_position=&#8221;below_title&#8221; category_style=&#8221;underline&#8221; category_display=&#8221;default&#8221; additional_meta_size=&#8221;default&#8221; custom_fields_location=&#8221;before_post_meta&#8221; grid_style=&#8221;content_under_image&#8221; card_design=&#8221;yes&#8221; card_bg_color=&#8221;#1f2125&#8243; card_bg_color_hover=&#8221;#25272b&#8221; content_under_image_text_align=&#8221;center&#8221; text_color=&#8221;light&#8221; hover_effect=&#8221;none&#8221; border_radius=&#8221;10px&#8221; card_design_bg_color=&#8221;#00cae8&#8243; posts_per_page=&#8221;45&#8243; css_class_name=&#8221;nectar-browser-window-style&#8221; display_type=&#8221;grid&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;13%&#8221; bottom_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; enable_gradient=&#8221;true&#8221; overlay_strength=&#8221;1&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_color=&#8221;#f4f4f4&#8243; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;40%&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;curve_opacity&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-664","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/prokat.k-tech.gr\/el\/wp-json\/wp\/v2\/pages\/664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prokat.k-tech.gr\/el\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/prokat.k-tech.gr\/el\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/prokat.k-tech.gr\/el\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prokat.k-tech.gr\/el\/wp-json\/wp\/v2\/comments?post=664"}],"version-history":[{"count":2,"href":"https:\/\/prokat.k-tech.gr\/el\/wp-json\/wp\/v2\/pages\/664\/revisions"}],"predecessor-version":[{"id":954,"href":"https:\/\/prokat.k-tech.gr\/el\/wp-json\/wp\/v2\/pages\/664\/revisions\/954"}],"wp:attachment":[{"href":"https:\/\/prokat.k-tech.gr\/el\/wp-json\/wp\/v2\/media?parent=664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}